{"id":12100,"date":"2026-09-01T23:30:30","date_gmt":"2026-09-02T02:30:30","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/noticias\/vira-copos-lidera-serie-b-de-rochedo-de-minas-apos-terceira-rodada\/"},"modified":"2026-09-01T23:30:30","modified_gmt":"2026-09-02T02:30:30","slug":"vira-copos-lidera-serie-b-de-rochedo-de-minas-apos-terceira-rodada","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/noticias\/vira-copos-lidera-serie-b-de-rochedo-de-minas-apos-terceira-rodada\/","title":{"rendered":"Vira Copos lidera S\u00e9rie B de Rochedo de Minas ap\u00f3s terceira rodada"},"content":{"rendered":"<p><i>Equipe mant\u00e9m 100% de aproveitamento e se destaca na competi\u00e7\u00e3o.<\/i><\/p>\n<hr>\n<p>No \u00faltimo s\u00e1bado (29), o Est\u00e1dio Laerte Medina foi palco da terceira rodada do Campeonato da S\u00e9rie B de Rochedo de Minas. A equipe do Vira Copos conquistou uma vit\u00f3ria importante sobre o PPG, garantindo um resultado de 1 a 0 e mantendo seu aproveitamento de 100% na competi\u00e7\u00e3o.<\/p>\n<p>Com essa vit\u00f3ria, o Vira Copos disparou na lideran\u00e7a isolada da S\u00e9rie B, somando um total de 9 pontos. O destaque da partida foi o craque Egon, que teve uma atua\u00e7\u00e3o decisiva e contribuiu para o sucesso da equipe.<\/p>\n<p>Al\u00e9m do jogo do Vira Copos, a rodada tamb\u00e9m contou com a vit\u00f3ria do Ressaca, que venceu o Sub-20 por 2 a 0, destacando-se o jogador Adriano, eleito o melhor em campo. Outro confronto da rodada viu o B\u00e1v\u00e1ros superar o Botafogo por 2 a 1, com Barral se destacando como o craque do jogo.<\/p>\n<p>A classifica\u00e7\u00e3o atualizada reflete o bom desempenho do Vira Copos, que se mostra forte candidato ao t\u00edtulo da competi\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vira Copos mant\u00e9m 100% de aproveitamento e dispara na lideran\u00e7a da S\u00e9rie B de Rochedo de Minas.<\/p>\n","protected":false},"author":5,"featured_media":3314,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1363,4367],"tags":[8455,1819,1944,8626,8627],"cidade_regiao":[],"guia_cidade":[],"class_list":["post-12100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes","category-regionais","tag-campeonato","tag-futebol","tag-rochedo-de-minas","tag-serie-b","tag-vira-copos"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/12100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=12100"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/12100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3314"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=12100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=12100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=12100"},{"taxonomy":"cidade_regiao","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/cidade_regiao?post=12100"},{"taxonomy":"guia_cidade","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/guia_cidade?post=12100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}