{"id":4181,"date":"2026-03-28T07:55:42","date_gmt":"2026-03-28T10:55:42","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/policia\/carreta-tomba-na-br-116-em-leopoldina-e-prf-evita-saque-de-carga\/"},"modified":"2026-03-28T07:55:42","modified_gmt":"2026-03-28T10:55:42","slug":"carreta-tomba-na-br-116-em-leopoldina-e-prf-evita-saque-de-carga","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/policia\/carreta-tomba-na-br-116-em-leopoldina-e-prf-evita-saque-de-carga\/","title":{"rendered":"Carreta tomba na BR-116 em Leopoldina e PRF evita saque de carga"},"content":{"rendered":"<p><i>Acidente ocorreu na manh\u00e3 desta sexta-feira com ve\u00edculo carregado de caf\u00e9<\/i><\/p>\n<hr>\n<p>Um acidente envolvendo uma carreta rodotrem foi registrado na manh\u00e3 desta sexta-feira (27) na BR-116, em Leopoldina, na altura do km 779,7. O tombamento aconteceu por volta das 7h30, quando a segunda carreta do conjunto, que transportava o cont\u00eainer traseiro, acabou tombando ap\u00f3s uma curva acentuada. O ve\u00edculo estava carregado com sacas de caf\u00e9 do munic\u00edpio de Espera Feliz, com destino ao Rio de Janeiro, de onde a carga seria exportada para os Estados Unidos.<\/p>\n<p>Ap\u00f3s o acidente, houve um in\u00edcio de saque da carga, mas a situa\u00e7\u00e3o foi rapidamente controlada pela Pol\u00edcia Rodovi\u00e1ria Federal (PRF), que atuou no local e conseguiu conter a a\u00e7\u00e3o. As circunst\u00e2ncias do acidente ainda est\u00e3o sendo apuradas. Felizmente, n\u00e3o houve registro de feridos no incidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma carreta carregada com caf\u00e9 tombou na BR-116 em Leopoldina, mas PRF evitou saque da carga.<\/p>\n","protected":false},"author":5,"featured_media":3437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1361],"tags":[1677,1782,2618,1410,2351],"class_list":["post-4181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-acidente","tag-br-116","tag-cafe","tag-leopoldina","tag-prf"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/4181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=4181"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/4181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3437"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=4181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=4181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=4181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}