{"id":4182,"date":"2026-03-28T07:55:57","date_gmt":"2026-03-28T10:55:57","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/policia\/acidente-na-br-267-deixa-motorista-ferido-e-interdita-rodovia-em-guarara-2\/"},"modified":"2026-03-28T07:55:57","modified_gmt":"2026-03-28T10:55:57","slug":"acidente-na-br-267-deixa-motorista-ferido-e-interdita-rodovia-em-guarara-2","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/policia\/acidente-na-br-267-deixa-motorista-ferido-e-interdita-rodovia-em-guarara-2\/","title":{"rendered":"Acidente na BR-267 deixa motorista ferido e interdita rodovia em Guarar\u00e1"},"content":{"rendered":"<p><i>Batida entre carreta e caminh\u00e3o provoca desvio de tr\u00e2nsito e atendimento m\u00e9dico.<\/i><\/p>\n<hr>\n<p>Um acidente envolvendo uma carreta e um caminh\u00e3o interditou um trecho da BR-267, em Guarar\u00e1, a 45 km de Juiz de Fora, na manh\u00e3 desta ter\u00e7a-feira, 28 de mar\u00e7o. O impacto da colis\u00e3o fez com que a carreta tombasse \u00e0s margens da rodovia, enquanto o caminh\u00e3o ficou atravessado na pista. O motorista do caminh\u00e3o precisou ser socorrido pelo Samu e foi encaminhado ao Hospital de Pronto Socorro (HPS) de Juiz de Fora, apresentando ferimentos. O condutor da carreta, por sua vez, n\u00e3o se feriu e optou por n\u00e3o receber atendimento m\u00e9dico.<\/p>\n<p>Devido ao acidente, a rodovia foi interditada para garantir a seguran\u00e7a dos motoristas que transitam pela regi\u00e3o. O tr\u00e1fego foi desviado para dentro da cidade de Guarar\u00e1, provocando congestionamentos no local. As autoridades est\u00e3o trabalhando para liberar a pista o mais r\u00e1pido poss\u00edvel e evitar maiores transtornos aos usu\u00e1rios da BR-267.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um acidente na BR-267 em Guarar\u00e1 deixou um motorista ferido e interditou a rodovia, exigindo desvio de tr\u00e2nsito.<\/p>\n","protected":false},"author":5,"featured_media":3437,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1361],"tags":[1677,2183,1264,1795,1954],"class_list":["post-4182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-acidente","tag-guarara","tag-juiz-de-fora","tag-rodovia","tag-samu"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/4182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=4182"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/4182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3437"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=4182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=4182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=4182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}