{"id":6228,"date":"2026-05-12T15:31:26","date_gmt":"2026-05-12T18:31:26","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/politica\/justica-suspende-processo-de-cassacao-do-vereador-devail-gomes-em-muriae\/"},"modified":"2026-05-12T15:31:26","modified_gmt":"2026-05-12T18:31:26","slug":"justica-suspende-processo-de-cassacao-do-vereador-devail-gomes-em-muriae","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/politica\/justica-suspende-processo-de-cassacao-do-vereador-devail-gomes-em-muriae\/","title":{"rendered":"Justi\u00e7a suspende processo de cassa\u00e7\u00e3o do vereador Devail Gomes em Muria\u00e9"},"content":{"rendered":"<p><i>Decis\u00e3o foi tomada ap\u00f3s an\u00e1lise de recursos apresentados pela defesa do parlamentar.<\/i><\/p>\n<hr>\n<p>A Justi\u00e7a de Muria\u00e9 decidiu suspender o processo de cassa\u00e7\u00e3o do vereador Devail Gomes. A decis\u00e3o foi proferida ap\u00f3s a an\u00e1lise de recursos apresentados pela defesa do parlamentar, que contestou os motivos que levaram \u00e0 abertura do processo. Com a suspens\u00e3o, Gomes mant\u00e9m seu cargo e as fun\u00e7\u00f5es legislativas, enquanto a situa\u00e7\u00e3o \u00e9 reavaliada.<\/p>\n<p>O vereador, que tem enfrentado uma s\u00e9rie de acusa\u00e7\u00f5es, se mostrou aliviado com a decis\u00e3o e afirmou que continuar\u00e1 trabalhando em prol da comunidade. A defesa de Gomes argumentou que as acusa\u00e7\u00f5es n\u00e3o tinham fundamento e que o processo estava sendo conduzido de maneira irregular.<\/p>\n<p>A suspens\u00e3o do processo \u00e9 uma vit\u00f3ria para o vereador, que agora poder\u00e1 se dedicar ao seu mandato sem a press\u00e3o da cassa\u00e7\u00e3o. A expectativa \u00e9 que o caso seja reavaliado em breve, garantindo o direito de defesa do parlamentar e a transpar\u00eancia nas a\u00e7\u00f5es da C\u00e2mara Municipal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a de Muria\u00e9 suspendeu o processo de cassa\u00e7\u00e3o do vereador Devail Gomes, permitindo que ele continue exercendo seu mandato.<\/p>\n","protected":false},"author":5,"featured_media":3323,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1360],"tags":[1903,1988,1736,1249,1902],"class_list":["post-6228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-cassacao","tag-devail-gomes","tag-justica","tag-muriae","tag-vereador"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/6228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=6228"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/6228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3323"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=6228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=6228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=6228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}