{"id":6255,"date":"2026-05-12T21:33:12","date_gmt":"2026-05-13T00:33:12","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/policia\/caminhonete-sem-freio-atropela-tres-homens-em-ibirite\/"},"modified":"2026-05-12T21:33:12","modified_gmt":"2026-05-13T00:33:12","slug":"caminhonete-sem-freio-atropela-tres-homens-em-ibirite","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/policia\/caminhonete-sem-freio-atropela-tres-homens-em-ibirite\/","title":{"rendered":"Caminhonete sem freio atropela tr\u00eas homens em Ibirit\u00e9"},"content":{"rendered":"<p><i>Acidente ocorreu na manh\u00e3 desta ter\u00e7a-feira, enquanto v\u00edtimas aguardavam para ir ao trabalho.<\/i><\/p>\n<hr>\n<p>Tr\u00eas homens ficaram feridos ap\u00f3s serem atropelados por uma caminhonete na manh\u00e3 desta ter\u00e7a-feira (12), em Ibirit\u00e9, na Grande Belo Horizonte. O acidente aconteceu na avenida Presidente Tancredo de Almeida Neves, no bairro Palmares A, quando o motorista de uma Fiat Fiorino supostamente perdeu o controle do ve\u00edculo devido a uma falha nos freios.<\/p>\n<p>As v\u00edtimas, que aguardavam para ir ao trabalho, foram atingidas e uma delas ficou parcialmente debaixo do ve\u00edculo, sendo resgatada pelos bombeiros. Os tr\u00eas homens estavam conscientes e apresentaram escoria\u00e7\u00f5es. Eles foram socorridos pelo Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu).<\/p>\n<p>Ap\u00f3s o atropelamento, a caminhonete ainda colidiu contra o muro e a porta de uma barbearia localizada \u00e0s margens da avenida. O propriet\u00e1rio do estabelecimento, Lucas Henrique, relatou que foi informado por vizinhos sobre a situa\u00e7\u00e3o. &#8220;Meu vizinho me ligou falando que o motorista desceu em alta velocidade e perdeu o controle. Os moradores estavam esperando para ir trabalhar quando foram atingidos&#8221;, contou.<\/p>\n<p>Lucas tamb\u00e9m mencionou que a batida causou danos na estrutura do im\u00f3vel, que era utilizada para conter a enxurrada no local. Equipes da Pol\u00edcia Militar, Pol\u00edcia Civil e peritos compareceram ao local do acidente. Segundo os bombeiros, n\u00e3o havia ind\u00edcios de consumo de bebida alco\u00f3lica por parte do motorista, e as causas do acidente est\u00e3o sendo investigadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas homens ficaram feridos ap\u00f3s serem atropelados por uma caminhonete em Ibirit\u00e9, na manh\u00e3 desta ter\u00e7a-feira.<\/p>\n","protected":false},"author":5,"featured_media":3377,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1361],"tags":[1677,1384,1262,4334,1954],"class_list":["post-6255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-acidente","tag-atropelamento","tag-corpo-de-bombeiros","tag-ibirite","tag-samu"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/6255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=6255"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/6255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3377"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=6255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=6255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=6255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}