{"id":9431,"date":"2026-07-15T10:33:49","date_gmt":"2026-07-15T13:33:49","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/noticias\/ginasio-em-juiz-de-fora-e-nomeado-em-homenagem-ao-jornalista-renato-salles\/"},"modified":"2026-07-15T10:33:49","modified_gmt":"2026-07-15T13:33:49","slug":"ginasio-em-juiz-de-fora-e-nomeado-em-homenagem-ao-jornalista-renato-salles","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/noticias\/ginasio-em-juiz-de-fora-e-nomeado-em-homenagem-ao-jornalista-renato-salles\/","title":{"rendered":"Gin\u00e1sio em Juiz de Fora \u00e9 nomeado em homenagem ao jornalista Renato Salles"},"content":{"rendered":"<p><i>Renatinho, falecido em abril, foi reconhecido por sua contribui\u00e7\u00e3o ao jornalismo local.<\/i><\/p>\n<hr>\n<p>A quadra da Secretaria de Esportes de Juiz de Fora agora se chama Gin\u00e1sio Jornalista Renato Salles, em uma homenagem ao jornalista que faleceu em 13 de abril de 2023, aos 47 anos. A mudan\u00e7a de nome foi oficializada nesta quarta-feira (15) ap\u00f3s a san\u00e7\u00e3o de um projeto de lei proposto pela vereadora K\u00e1tia Franco (PSB).<\/p>\n<p>Natural de Juiz de Fora e morador do bairro Santa Terezinha, Renato Salles, conhecido carinhosamente como Renatinho, formou-se em Comunica\u00e7\u00e3o Social pela Universidade Federal de Juiz de Fora (UFJF). Sua carreira no jornalismo come\u00e7ou como estagi\u00e1rio na TV Panorama, onde se destacou e, posteriormente, trabalhou em ve\u00edculos como o jornal JF Hoje e a Tribuna de Minas, cobrindo temas de pol\u00edtica e esporte.<\/p>\n<p>Renato Salles enfrentou uma grave crise de sa\u00fade em agosto de 2023, quando sofreu uma parada cardiorrespirat\u00f3ria decorrente de uma crise de asma, levando-o a ficar em coma at\u00e9 seu falecimento. Em 2025, sua fam\u00edlia recebeu a Comenda Halfeld, uma honraria concedida pela Prefeitura de Juiz de Fora a pessoas que se destacam em diversas \u00e1reas de interesse da cidade.<\/p>\n<p>Agora, com o nome do gin\u00e1sio em sua homenagem, a mem\u00f3ria de Renatinho permanecer\u00e1 viva em um espa\u00e7o esportivo p\u00fablico, simbolizando sua import\u00e2ncia para a comunidade local.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gin\u00e1sio em Juiz de Fora \u00e9 nomeado em homenagem ao jornalista Renato Salles, que faleceu em abril de 2023.<\/p>\n","protected":false},"author":5,"featured_media":3303,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1364,4367],"tags":[1813,3299,1264,7609,7610],"cidade_regiao":[],"guia_cidade":[],"class_list":["post-9431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-regionais","tag-homenagem","tag-jornalismo","tag-juiz-de-fora","tag-renato-salles","tag-secretaria-de-esportes"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/9431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=9431"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/9431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3303"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=9431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=9431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=9431"},{"taxonomy":"cidade_regiao","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/cidade_regiao?post=9431"},{"taxonomy":"guia_cidade","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/guia_cidade?post=9431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}