{"id":9526,"date":"2026-07-17T16:31:55","date_gmt":"2026-07-17T19:31:55","guid":{"rendered":"https:\/\/guiacataguases.com.br\/nova\/noticias\/agenda-cultural-mumuzinho-e-anavitoria-se-apresentam-em-juiz-de-fora\/"},"modified":"2026-07-17T16:31:55","modified_gmt":"2026-07-17T19:31:55","slug":"agenda-cultural-mumuzinho-e-anavitoria-se-apresentam-em-juiz-de-fora","status":"publish","type":"post","link":"https:\/\/guiacataguases.com.br\/nova\/noticias\/agenda-cultural-mumuzinho-e-anavitoria-se-apresentam-em-juiz-de-fora\/","title":{"rendered":"Agenda Cultural: Mumuzinho e Anavit\u00f3ria se apresentam em Juiz de Fora"},"content":{"rendered":"<p><i>Confira os principais eventos deste fim de semana na Zona da Mata<\/i><\/p>\n<hr>\n<p>O fim de semana promete ser animado em Juiz de Fora e regi\u00e3o, com uma agenda cultural repleta de atra\u00e7\u00f5es. Entre os destaques, Mumuzinho e Anavit\u00f3ria se apresentam em diferentes locais da cidade, al\u00e9m de eventos em Argirita, Paiva e S\u00e3o Jo\u00e3o del Rei.<\/p>\n<p>Em Juiz de Fora, Anavit\u00f3ria far\u00e1 um show no Cine-Theatro Central no domingo, dia 19, \u00e0s 20h30. Os ingressos j\u00e1 est\u00e3o dispon\u00edveis para compra online. No s\u00e1bado, dia 18, o evento &#8216;360 nas Alturas&#8217; contar\u00e1 com a presen\u00e7a de Mumuzinho, Grupo Alquimia e DJ Morango a partir das 15h, no Univ\u00e9rtix, localizado na rua Pedro Celeste, 701, no bairro Cruzeiro do Sul.<\/p>\n<p>Outro evento em destaque \u00e9 o &#8216;TuDiBaum&#8217;, que acontece entre sexta (17) e domingo (19) e novamente no final de semana seguinte, no estacionamento do Shopping Jardim Norte. A entrada \u00e9 gratuita mediante a doa\u00e7\u00e3o de 1 kg de alimento, e a programa\u00e7\u00e3o inclui diversas atra\u00e7\u00f5es musicais, como Ligeirinho Sanfoneiro e DJ Kalango.<\/p>\n<p>Em Lima Duarte, o Ibitipoca Blues ser\u00e1 realizado de quinta (16) a domingo (19), com diversas atra\u00e7\u00f5es em S\u00e3o Jos\u00e9 dos Lopes. J\u00e1 em Argirita, a Expoagro 2026 ocorrer\u00e1 de sexta (17) a domingo (19), com shows de Mumuzinho e outros artistas, com entrada gratuita.<\/p>\n<p>Por fim, S\u00e3o Jo\u00e3o del Rei receber\u00e1 o 36\u00ba Inverno Cultural da UFSJ, que contar\u00e1 com uma programa\u00e7\u00e3o variada, incluindo um show de Beto Guedes no s\u00e1bado, dia 18, no Largo de S\u00e3o Francisco, tamb\u00e9m com entrada gratuita. Os eventos prometem agitar a regi\u00e3o e oferecer op\u00e7\u00f5es de entretenimento para todos os gostos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mumuzinho e Anavit\u00f3ria s\u00e3o os destaques da agenda cultural deste fim de semana em Juiz de Fora e regi\u00e3o, com eventos em diversas cidades.<\/p>\n","protected":false},"author":5,"featured_media":3303,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1364,8070,4367],"tags":[7695,1510,1511,1264,7696],"cidade_regiao":[],"guia_cidade":[],"class_list":["post-9526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-juiz-de-fora","category-regionais","tag-anavitoria","tag-cultura","tag-eventos","tag-juiz-de-fora","tag-mumuzinho"],"_links":{"self":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/9526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/comments?post=9526"}],"version-history":[{"count":0,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/posts\/9526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media\/3303"}],"wp:attachment":[{"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/media?parent=9526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/categories?post=9526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/tags?post=9526"},{"taxonomy":"cidade_regiao","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/cidade_regiao?post=9526"},{"taxonomy":"guia_cidade","embeddable":true,"href":"https:\/\/guiacataguases.com.br\/nova\/wp-json\/wp\/v2\/guia_cidade?post=9526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}